{"id":79692001,"date":"2024-01-25T17:47:04","date_gmt":"2024-01-25T20:47:04","guid":{"rendered":"https:\/\/blog.grancursosonline.com.br\/?p=79692001"},"modified":"2024-01-25T17:52:54","modified_gmt":"2024-01-25T20:52:54","slug":"ivalda-oliveira-administracao-gran-faculdade","status":"publish","type":"post","link":"https:\/\/faculdade.grancursosonline.com.br\/blog\/ivalda-oliveira-administracao-gran-faculdade\/","title":{"rendered":"Ivalda persistiu e hoje faz Administra\u00e7\u00e3o na Gran Faculdade!"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">O anivers\u00e1rio de 1 ano da <a href=\"https:\/\/faculdade.grancursosonline.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">Gran Faculdade<\/a> se aproxima e para celebrar, estamos apresentando o depoimento de alguns alunos que confiam e acreditam na qualidade dos nossos cursos. Hoje vamos conhecer um pouco sobre a hist\u00f3ria da Ivalda de Oliveira, aluna do <a href=\"https:\/\/faculdade.grancursosonline.com.br\/curso\/administracao\/\">cur<\/a><a href=\"https:\/\/faculdade.grancursosonline.com.br\/curso\/administracao\/\" target=\"_blank\" rel=\"noreferrer noopener\">s<\/a><a href=\"https:\/\/faculdade.grancursosonline.com.br\/curso\/administracao\/\">o de Administra\u00e7\u00e3o<\/a>. Vamos l\u00e1?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Acompanhando o artigo para saber mais ou navegue pelo \u00edndice:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"#ivalda-oliveira\">Quem \u00e9 Ivalda de Oliveira?<\/a><\/li>\n\n\n\n<li><a href=\"#pontos-positivos\">O que voc\u00ea mais gosta como aluna da Gran Faculdade?<\/a><\/li>\n\n\n\n<li><a href=\"#plaos-profissionais\">Quais os seus planos para a vida profissional?<\/a><\/li>\n\n\n\n<li><a href=\"#dicas\">Que dica voc\u00ea daria para si mesmo quando come\u00e7ou?<\/a><\/li>\n<\/ul>\n\n\n<div class=\"container-tabela\"><table border=\"1\" bgcolor=\"aliceblue\">\n<tbody>\n<tr>\n<td><strong>Destaques:<\/strong>\n<ul>\n<li><a href=\"https:\/\/blog.grancursosonline.com.br\/faculdade-de-administracao\/\" target=\"_blank\" rel=\"noopener\">Faculdade de Administra\u00e7\u00e3o: como \u00e9 o curso e quanto custa?<\/a><\/li>\n<li><a href=\"https:\/\/blog.grancursosonline.com.br\/areas-da-administracao\/\" target=\"_blank\" rel=\"noopener\">Confira as principais \u00e1reas da administra\u00e7\u00e3o e suas fun\u00e7\u00f5es<\/a> <\/li>\n<li><a href=\"https:\/\/blog.grancursosonline.com.br\/especializacao-em-administracao\/\" target=\"_blank\" rel=\"noopener\">Especializa\u00e7\u00e3o em Administra\u00e7\u00e3o: 6 cursos em alta!<\/a><\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table><\/div>\n\n\n<h2 class=\"wp-block-heading\" id=\"ivalda-oliveira\">Quem \u00e9 Ivalda de Oliveira?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Aqui no Gran acreditamos que a educa\u00e7\u00e3o est\u00e1 al\u00e9m de qualquer tipo de fronteira, pois atendemos estudantes de todo o pa\u00eds. A Ivalda de Oliveira \u00e9 de Pernambuco, adora cinema, praia e fazer artesanato, o que considera um tipo de terapia que ainda consegue fazer uma renda extra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Apaixonada por livros, considera eles uma parte importante da sua vida. Ivalda l\u00ea de tudo, mas principalmente biografias, cl\u00e1ssicos da literatura e desenvolvimento pessoal.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Antes de ser nossa aluna, chegou a come\u00e7ar o curso de <a href=\"https:\/\/faculdade.grancursosonline.com.br\/curso\/administracao\/\">Administra\u00e7\u00e3o<\/a> da Universidade Federal de Pernambuco, mas engravidou na \u00e9poca e n\u00e3o conseguiu concluir o curso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esse momento foi muito dif\u00edcil para ela, que chorou muito. Acabou perdendo o v\u00ednculo com a institui\u00e7\u00e3o e com a rotina familiar da \u00e9poca, filho pequeno e muitas despesas, fazer um curso superior era invi\u00e1vel.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Naquela \u00e9poca, 13 anos atr\u00e1s, o Gran ainda n\u00e3o existia, mas hoje ainda conseguimos ajudar a Ivalda a realizar esse sonho:<\/p>\n\n\n<p style=\"padding-left: 80px;\"><em>Passado 13 anos, o Gran lan\u00e7ou a Faculdade, foi um sonho&#8230;eu retomei meu objetivo e hoje curso Administra\u00e7\u00e3o. Estou muito feliz!<\/em><\/p>\n\n\n<p class=\"wp-block-paragraph\">Hoje ela \u00e9 servidora p\u00fablica da prefeitura de Recife, onde atua em uma unidade de Per\u00edcias M\u00e9dicas. Ela vive com o filho, que tem 13 anos, e juntos eles se organizam no dia a dia.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"pontos-positivos\">O que voc\u00ea mais gosta como aluna da Gran Faculdade?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ivalda nos contou que sempre estuda \u00e0 noite, depois dos afazeres dom\u00e9sticos, e assiste muitas aulas no \u00f4nibus, aguardando uma consulta ou qualquer brecha que encontre durante o dia.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, com a Gran Faculdade, ela tamb\u00e9m consegue se organizar para estudar aos finais de semana e conciliar a vida pessoal, passar um tempo com o filho e outros cuidados pessoais.<\/p>\n\n\n<p style=\"padding-left: 80px;\"><em>Quanto ao meu desenvolvimento s\u00f3 tenho a festejar, tanto pela qualidade de ensino quanto por minha dedica\u00e7\u00e3o. \u00c9 uma luta, mas estou feliz e realizada. [&#8230;] A qualidade de ensino aliada a um pre\u00e7o acess\u00edvel. A inova\u00e7\u00e3o tecnol\u00f3gica do Gran entrega muitos benef\u00edcios para os alunos.<\/em><\/p>\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, ela destaca que o cuidado do Gran com os estudantes sempre a surpreende de uma forma positiva.<\/p>\n\n\n<p style=\"padding-left: 80px;\"><em>Nunca imaginei fazer um curso EAD e me sentir t\u00e3o pr\u00f3xima da institui\u00e7\u00e3o, dos professores&#8230;.enfim, estou muito feliz pelo aprendizado e pela oportunidade de fazer essa gradua\u00e7\u00e3o.\u00a0<\/em><\/p>\n\n\n<h2 class=\"wp-block-heading\" id=\"planos-profissionais\">Quais os seus planos para a vida profissional?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Seu interesse na \u00e1rea de Administra\u00e7\u00e3o existe desde sempre, tanto \u00e9 que hoje atua em uma fun\u00e7\u00e3o correlata no seu emprego atual.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seu principal objetivo \u00e9 conseguir prestar concurso de n\u00edvel superior para a \u00e1rea administrativa, crescer profissionalmente e obter um sal\u00e1rio maior para poder viver com mais conforto e oportunidades.<\/p>\n\n\n<p style=\"padding-left: 80px;\"><em>Estou evoluindo e me desenvolvendo cada vez mais. Tenho aplicado meus conhecimentos no dia a dia e me sentindo realizada. Al\u00e9m disso, pretendo fazer concurso como Administradora, ampliar meu leque op\u00e7\u00f5es na \u00e1rea de concurso com minha gradua\u00e7\u00e3o.\u00a0<\/em><\/p>\n\n\n<p class=\"wp-block-paragraph\">Ivalda conta que ainda que seu cargo seja de n\u00edvel m\u00e9dio, ela reconhece que desde o come\u00e7o do curso j\u00e1 se sente mais preparada para as demandas da sua unidade de trabalho.<\/p>\n\n\n<p style=\"padding-left: 80px;\"><em>Apenas com o conhecimento nesse come\u00e7o de curso, j\u00e1 me sinto mais preparada para as demandas da unidade onde trabalho e participando mais ativamente dos processos. O que provavelmente trar\u00e1 melhorias em todos os aspectos profissionais, \u00e9 fato.<\/em><\/p>\n\n\n<h2 class=\"wp-block-heading\" id=\"dicas\">Que dica voc\u00ea daria para si mesmo quando come\u00e7ou?&nbsp;<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Pedimos que a Ivalda deixasse uma dica ou conselho para quem est\u00e1 pensando em come\u00e7ar a faculdade:<\/p>\n\n\n<p style=\"padding-left: 80px;\"><em>Nunca pare de estudar, de aprender, de buscar conhecimento. Saia de sua zona conforto e n\u00e3o se importe com o que os outros dizem&#8230;s\u00f3 voc\u00ea poder\u00e1 conquistar seus objetivos, ningu\u00e9m mais! Arregace as mangas e continue seguindo em frente! Assim, a cada dia voc\u00ea se aproxima cada vez mais do seu sonho.<\/em><\/p>\n\n\n<p class=\"wp-block-paragraph\">Ivalda n\u00e3o desistiu do seu sonho de fazer uma gradua\u00e7\u00e3o e segue firme com seu objetivo. Aqui no <a href=\"https:\/\/www.grancursosonline.com.br\/\">Gran<\/a>, nosso objetivo \u00e9 te acompanhar a evoluir a sua qualidade de vida, suas habilidades t\u00e9cnicas e tamb\u00e9m aspectos interpessoais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com nossos <a href=\"https:\/\/faculdade.grancursosonline.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">cursos de gradua\u00e7\u00e3o<\/a> 100% digitais, voc\u00ea consegue tudo isso no seu ritmo. Contamos com professores mestres e doutores e uma s\u00e9rie de ferramentas de estudo para otimizar o seu aprendizado. Tudo isso pagando valores acess\u00edveis e que cabem no seu bolso:<\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h3 class=\"wp-block-heading\" id=\"h-cursos-de-graduacao-ead\">Cursos de gradua\u00e7\u00e3o EAD<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00e3o <a href=\"https:\/\/faculdade.grancursosonline.com.br\/nossos-cursos\/\" target=\"_blank\" rel=\"noreferrer noopener\">mais de 30 op\u00e7\u00f5es de cursos de gradua\u00e7\u00e3o EAD<\/a> com dura\u00e7\u00e3o a partir de 2 anos na Gran Faculdade, ideais para quem quer se destacar em uma carreira no setor p\u00fablico ou privado. Escolha o seu e aproveite a entrada imediata para come\u00e7ar a conquistar seu diploma hoje mesmo! <\/p>\n<\/div><\/div>\n\n\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-vem-pra-gran-faculdade\">Vem pra Gran Faculdade!<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A Gran Faculdade vem mudando a vida de milhares de pessoas por meio de cursos \u00e0 dist\u00e2ncia de <a href=\"https:\/\/faculdade.grancursosonline.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">gradua\u00e7\u00e3o<\/a>, <a href=\"https:\/\/pos.grancursosonline.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">p\u00f3s-gradua\u00e7\u00e3o<\/a> e <a href=\"https:\/\/pos.grancursosonline.com.br\/mba\" target=\"_blank\" rel=\"noreferrer noopener\">MBA<\/a>. Seja no digital ou em nosso <a href=\"https:\/\/presencial.grancursosonline.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">Campus Presencial em Curitiba<\/a>, a nossa miss\u00e3o \u00e9 transformar a educa\u00e7\u00e3o superior.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como parte de Sistema Gran de Ensino, que \u00e9 reconhecido como marca aprovadora h\u00e1 mais de 10 anos, constru\u00edmos uma renomada reputa\u00e7\u00e3o na \u00e1rea de educa\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Veja algumas de nossas conquistas:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Reconhecido pela Amazon como um dos projetos mais relevantes do mundo na \u00e1rea de Tecnologia e Educa\u00e7\u00e3o;<\/li>\n\n\n\n<li>Foi eleito pelo Project Management Institute (PMI), um dos 50 Projetos Mais Influentes do mundo;<\/li>\n\n\n\n<li>Somos o site de educa\u00e7\u00e3o mais acessado do Brasil;<\/li>\n\n\n\n<li>Somos avaliados com a nota m\u00e1xima pelo MEC;<\/li>\n\n\n\n<li>Aqui o semestre come\u00e7a quando quiser: entrada imediata e cont\u00ednua!<\/li>\n\n\n\n<li>Melhores pre\u00e7os do mercado;<\/li>\n\n\n\n<li>Mais de 500 mil alunos pagantes e mais de 1000 funcion\u00e1rios;<\/li>\n\n\n\n<li>Diversas ferramentas de estudo: PDFs, audiobooks, mapas mentais, videoaulas, quest\u00f5es, gerenciador de estudos e muito mais!<\/li>\n\n\n\n<li>Professores experientes e capacitados;<\/li>\n\n\n\n<li>Acesso imediato e 100% online.<\/li>\n<\/ul>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><strong><a href=\"https:\/\/faculdade.grancursosonline.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">Quero ser aluno da Gran Faculdade!<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O anivers\u00e1rio de 1 ano da Gran Faculdade se aproxima e para celebrar, estamos apresentando o depoimento de alguns alunos que confiam e acreditam na qualidade dos nossos cursos. Hoje vamos conhecer um pouco sobre a hist\u00f3ria da Ivalda de Oliveira, aluna do curso de Administra\u00e7\u00e3o. Vamos l\u00e1? Acompanhando o artigo para saber mais ou&hellip;<\/p>\n","protected":false},"author":486,"featured_media":79692011,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[218545,2],"tags":[],"class_list":["post-79692001","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-graduacao","category-ultimas-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ivalda persistiu e hoje faz Administra\u00e7\u00e3o na Gran Faculdade!<\/title>\n<meta name=\"description\" content=\"Conhe\u00e7a a hist\u00f3ria da Ivalda de Oliveira, aluna de Administra\u00e7\u00e3o da Gran Faculdade: ela adiou o seu sonho, mas n\u00e3o desistiu e hoje faz faculdade!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/faculdade.grancursosonline.com.br\/blog\/ivalda-oliveira-administracao-gran-faculdade\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ivalda persistiu e hoje faz Administra\u00e7\u00e3o na Gran Faculdade!\" \/>\n<meta property=\"og:description\" content=\"Conhe\u00e7a a hist\u00f3ria da Ivalda de Oliveira, aluna de Administra\u00e7\u00e3o da Gran Faculdade: ela adiou o seu sonho, mas n\u00e3o desistiu e hoje faz faculdade!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/faculdade.grancursosonline.com.br\/blog\/ivalda-oliveira-administracao-gran-faculdade\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Gran Faculdade\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/grancursosonline\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-25T20:47:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-25T20:52:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog-es-static.infra.grancursosonline.com.br\/wp-content\/uploads\/2024\/01\/25174542\/ivalda-oliveira%E2%80%93administracao-gran-faculdade.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"511\" \/>\n\t<meta property=\"og:image:height\" content=\"311\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Equipe Gran\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@gran_online\" \/>\n<meta name=\"twitter:site\" content=\"@gran_online\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipe Gran\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/ivalda-oliveira-administracao-gran-faculdade\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/ivalda-oliveira-administracao-gran-faculdade\/\"},\"author\":{\"name\":\"Equipe Gran\",\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/#\/schema\/person\/c05f350f8ea43a7138aaffc6a87bc5e0\"},\"headline\":\"Ivalda persistiu e hoje faz Administra\u00e7\u00e3o na Gran Faculdade!\",\"datePublished\":\"2024-01-25T20:47:04+00:00\",\"dateModified\":\"2024-01-25T20:52:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/ivalda-oliveira-administracao-gran-faculdade\/\"},\"wordCount\":887,\"commentCount\":11,\"publisher\":{\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/ivalda-oliveira-administracao-gran-faculdade\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blog-es-static.infra.grancursosonline.com.br\/wp-content\/uploads\/2024\/01\/25174542\/ivalda-oliveira%E2%80%93administracao-gran-faculdade.jpg\",\"articleSection\":[\"Gradua\u00e7\u00e3o Gran Faculdade\",\"\u00daltimas Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/faculdade.grancursosonline.com.br\/blog\/ivalda-oliveira-administracao-gran-faculdade\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/ivalda-oliveira-administracao-gran-faculdade\/\",\"url\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/ivalda-oliveira-administracao-gran-faculdade\/\",\"name\":\"Ivalda persistiu e hoje faz Administra\u00e7\u00e3o na Gran Faculdade!\",\"isPartOf\":{\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/ivalda-oliveira-administracao-gran-faculdade\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/ivalda-oliveira-administracao-gran-faculdade\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blog-es-static.infra.grancursosonline.com.br\/wp-content\/uploads\/2024\/01\/25174542\/ivalda-oliveira%E2%80%93administracao-gran-faculdade.jpg\",\"datePublished\":\"2024-01-25T20:47:04+00:00\",\"dateModified\":\"2024-01-25T20:52:54+00:00\",\"description\":\"Conhe\u00e7a a hist\u00f3ria da Ivalda de Oliveira, aluna de Administra\u00e7\u00e3o da Gran Faculdade: ela adiou o seu sonho, mas n\u00e3o desistiu e hoje faz faculdade!\",\"breadcrumb\":{\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/ivalda-oliveira-administracao-gran-faculdade\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/faculdade.grancursosonline.com.br\/blog\/ivalda-oliveira-administracao-gran-faculdade\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/ivalda-oliveira-administracao-gran-faculdade\/#primaryimage\",\"url\":\"https:\/\/blog-es-static.infra.grancursosonline.com.br\/wp-content\/uploads\/2024\/01\/25174542\/ivalda-oliveira%E2%80%93administracao-gran-faculdade.jpg\",\"contentUrl\":\"https:\/\/blog-es-static.infra.grancursosonline.com.br\/wp-content\/uploads\/2024\/01\/25174542\/ivalda-oliveira%E2%80%93administracao-gran-faculdade.jpg\",\"width\":511,\"height\":311},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/ivalda-oliveira-administracao-gran-faculdade\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gradua\u00e7\u00e3o Gran Faculdade\",\"item\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/graduacao\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ivalda persistiu e hoje faz Administra\u00e7\u00e3o na Gran Faculdade!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/#website\",\"url\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/\",\"name\":\"Blog Gran Faculdade\",\"description\":\"Tudo sobre ensino superior, p\u00f3s-gradua\u00e7\u00e3o, enem e carreira.\",\"publisher\":{\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/#organization\",\"name\":\"Gran Cursos Online\",\"url\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/blog-es-static.infra.grancursosonline.com.br\/wp-content\/uploads\/2019\/08\/03123934\/logo.png\",\"contentUrl\":\"https:\/\/blog-es-static.infra.grancursosonline.com.br\/wp-content\/uploads\/2019\/08\/03123934\/logo.png\",\"width\":300,\"height\":57,\"caption\":\"Gran Cursos Online\"},\"image\":{\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/grancursosonline\/\",\"https:\/\/x.com\/gran_online\",\"https:\/\/www.instagram.com\/grancursosonline\/\",\"https:\/\/www.youtube.com\/user\/grancursostv\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/#\/schema\/person\/c05f350f8ea43a7138aaffc6a87bc5e0\",\"name\":\"Equipe Gran\",\"sameAs\":[\"http:\/\/www.grancursosonline.com.br\"],\"url\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/author\/hugo-oliveira\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ivalda persistiu e hoje faz Administra\u00e7\u00e3o na Gran Faculdade!","description":"Conhe\u00e7a a hist\u00f3ria da Ivalda de Oliveira, aluna de Administra\u00e7\u00e3o da Gran Faculdade: ela adiou o seu sonho, mas n\u00e3o desistiu e hoje faz faculdade!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/faculdade.grancursosonline.com.br\/blog\/ivalda-oliveira-administracao-gran-faculdade\/","og_locale":"pt_BR","og_type":"article","og_title":"Ivalda persistiu e hoje faz Administra\u00e7\u00e3o na Gran Faculdade!","og_description":"Conhe\u00e7a a hist\u00f3ria da Ivalda de Oliveira, aluna de Administra\u00e7\u00e3o da Gran Faculdade: ela adiou o seu sonho, mas n\u00e3o desistiu e hoje faz faculdade!","og_url":"https:\/\/faculdade.grancursosonline.com.br\/blog\/ivalda-oliveira-administracao-gran-faculdade\/","og_site_name":"Blog Gran Faculdade","article_publisher":"https:\/\/www.facebook.com\/grancursosonline\/","article_published_time":"2024-01-25T20:47:04+00:00","article_modified_time":"2024-01-25T20:52:54+00:00","og_image":[{"width":511,"height":311,"url":"https:\/\/blog-es-static.infra.grancursosonline.com.br\/wp-content\/uploads\/2024\/01\/25174542\/ivalda-oliveira%E2%80%93administracao-gran-faculdade.jpg","type":"image\/jpeg"}],"author":"Equipe Gran","twitter_card":"summary_large_image","twitter_creator":"@gran_online","twitter_site":"@gran_online","twitter_misc":{"Written by":"Equipe Gran","Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/ivalda-oliveira-administracao-gran-faculdade\/#article","isPartOf":{"@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/ivalda-oliveira-administracao-gran-faculdade\/"},"author":{"name":"Equipe Gran","@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/#\/schema\/person\/c05f350f8ea43a7138aaffc6a87bc5e0"},"headline":"Ivalda persistiu e hoje faz Administra\u00e7\u00e3o na Gran Faculdade!","datePublished":"2024-01-25T20:47:04+00:00","dateModified":"2024-01-25T20:52:54+00:00","mainEntityOfPage":{"@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/ivalda-oliveira-administracao-gran-faculdade\/"},"wordCount":887,"commentCount":11,"publisher":{"@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/ivalda-oliveira-administracao-gran-faculdade\/#primaryimage"},"thumbnailUrl":"https:\/\/blog-es-static.infra.grancursosonline.com.br\/wp-content\/uploads\/2024\/01\/25174542\/ivalda-oliveira%E2%80%93administracao-gran-faculdade.jpg","articleSection":["Gradua\u00e7\u00e3o Gran Faculdade","\u00daltimas Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/faculdade.grancursosonline.com.br\/blog\/ivalda-oliveira-administracao-gran-faculdade\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/ivalda-oliveira-administracao-gran-faculdade\/","url":"https:\/\/faculdade.grancursosonline.com.br\/blog\/ivalda-oliveira-administracao-gran-faculdade\/","name":"Ivalda persistiu e hoje faz Administra\u00e7\u00e3o na Gran Faculdade!","isPartOf":{"@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/ivalda-oliveira-administracao-gran-faculdade\/#primaryimage"},"image":{"@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/ivalda-oliveira-administracao-gran-faculdade\/#primaryimage"},"thumbnailUrl":"https:\/\/blog-es-static.infra.grancursosonline.com.br\/wp-content\/uploads\/2024\/01\/25174542\/ivalda-oliveira%E2%80%93administracao-gran-faculdade.jpg","datePublished":"2024-01-25T20:47:04+00:00","dateModified":"2024-01-25T20:52:54+00:00","description":"Conhe\u00e7a a hist\u00f3ria da Ivalda de Oliveira, aluna de Administra\u00e7\u00e3o da Gran Faculdade: ela adiou o seu sonho, mas n\u00e3o desistiu e hoje faz faculdade!","breadcrumb":{"@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/ivalda-oliveira-administracao-gran-faculdade\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/faculdade.grancursosonline.com.br\/blog\/ivalda-oliveira-administracao-gran-faculdade\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/ivalda-oliveira-administracao-gran-faculdade\/#primaryimage","url":"https:\/\/blog-es-static.infra.grancursosonline.com.br\/wp-content\/uploads\/2024\/01\/25174542\/ivalda-oliveira%E2%80%93administracao-gran-faculdade.jpg","contentUrl":"https:\/\/blog-es-static.infra.grancursosonline.com.br\/wp-content\/uploads\/2024\/01\/25174542\/ivalda-oliveira%E2%80%93administracao-gran-faculdade.jpg","width":511,"height":311},{"@type":"BreadcrumbList","@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/ivalda-oliveira-administracao-gran-faculdade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/faculdade.grancursosonline.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Gradua\u00e7\u00e3o Gran Faculdade","item":"https:\/\/faculdade.grancursosonline.com.br\/blog\/graduacao\/"},{"@type":"ListItem","position":3,"name":"Ivalda persistiu e hoje faz Administra\u00e7\u00e3o na Gran Faculdade!"}]},{"@type":"WebSite","@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/#website","url":"https:\/\/faculdade.grancursosonline.com.br\/blog\/","name":"Blog Gran Faculdade","description":"Tudo sobre ensino superior, p\u00f3s-gradua\u00e7\u00e3o, enem e carreira.","publisher":{"@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/faculdade.grancursosonline.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/#organization","name":"Gran Cursos Online","url":"https:\/\/faculdade.grancursosonline.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/blog-es-static.infra.grancursosonline.com.br\/wp-content\/uploads\/2019\/08\/03123934\/logo.png","contentUrl":"https:\/\/blog-es-static.infra.grancursosonline.com.br\/wp-content\/uploads\/2019\/08\/03123934\/logo.png","width":300,"height":57,"caption":"Gran Cursos Online"},"image":{"@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/grancursosonline\/","https:\/\/x.com\/gran_online","https:\/\/www.instagram.com\/grancursosonline\/","https:\/\/www.youtube.com\/user\/grancursostv"]},{"@type":"Person","@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/#\/schema\/person\/c05f350f8ea43a7138aaffc6a87bc5e0","name":"Equipe Gran","sameAs":["http:\/\/www.grancursosonline.com.br"],"url":"https:\/\/faculdade.grancursosonline.com.br\/blog\/author\/hugo-oliveira\/"}]}},"_links":{"self":[{"href":"https:\/\/faculdade.grancursosonline.com.br\/blog\/wp-json\/wp\/v2\/posts\/79692001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/faculdade.grancursosonline.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/faculdade.grancursosonline.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/faculdade.grancursosonline.com.br\/blog\/wp-json\/wp\/v2\/users\/486"}],"replies":[{"embeddable":true,"href":"https:\/\/faculdade.grancursosonline.com.br\/blog\/wp-json\/wp\/v2\/comments?post=79692001"}],"version-history":[{"count":3,"href":"https:\/\/faculdade.grancursosonline.com.br\/blog\/wp-json\/wp\/v2\/posts\/79692001\/revisions"}],"predecessor-version":[{"id":79692015,"href":"https:\/\/faculdade.grancursosonline.com.br\/blog\/wp-json\/wp\/v2\/posts\/79692001\/revisions\/79692015"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/faculdade.grancursosonline.com.br\/blog\/wp-json\/wp\/v2\/media\/79692011"}],"wp:attachment":[{"href":"https:\/\/faculdade.grancursosonline.com.br\/blog\/wp-json\/wp\/v2\/media?parent=79692001"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/faculdade.grancursosonline.com.br\/blog\/wp-json\/wp\/v2\/categories?post=79692001"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/faculdade.grancursosonline.com.br\/blog\/wp-json\/wp\/v2\/tags?post=79692001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}