{"id":79752964,"date":"2025-04-09T18:10:44","date_gmt":"2025-04-09T21:10:44","guid":{"rendered":"https:\/\/faculdade.grancursosonline.com.br\/blog\/?p=79752964"},"modified":"2025-04-25T13:23:09","modified_gmt":"2025-04-25T16:23:09","slug":"depoimento-juliana-goncalves-pos-graduacao","status":"publish","type":"post","link":"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-juliana-goncalves-pos-graduacao\/","title":{"rendered":"Conhe\u00e7a a hist\u00f3ria de Juliana Gon\u00e7alves, aluna da gran p\u00f3s!"},"content":{"rendered":"\n<p>Apesar da rotina intensa e multifacetada, Juliana Gon\u00e7alves encontrou na P\u00f3s-gradua\u00e7\u00e3o em Direito Constitucional da Gran Faculdade n\u00e3o apenas uma aliada para o crescimento profissional, mas tamb\u00e9m um impulso para o desenvolvimento pessoal. Advogada, profissional de marketing e estudante dedicada, ela compartilhou sua experi\u00eancia com a institui\u00e7\u00e3o e revelou como tem conciliado seus objetivos com paix\u00e3o e resili\u00eancia.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/whatsapp.com\/channel\/0029VaG1sChI7Be7PNndhL43\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/blog-es-static.infra.grancursosonline.com.br\/wp-content\/uploads\/2025\/09\/09112354\/banner-wp-600x142-80.webp\" alt=\"Acesse o canal do WhatsApp da Gran Faculdade\" class=\"wp-image-79751904\"\/><\/a><\/figure>\n<\/div><\/div>\n<\/div>\n\n\n\n<p>Acompanhe o artigo para saber mais ou navegue pelo \u00edndice:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"#gran\">Por que a Gran Faculdade?<\/a><\/li>\n\n\n\n<li><a href=\"#profissional\">Trajet\u00f3ria Profissional<\/a><\/li>\n\n\n\n<li><a href=\"#pessoal\">Vida Pessoal<\/a><\/li>\n\n\n\n<li><a href=\"#dicas\">Dicas e Perspectivas para o futuro<\/a><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-por-que-a-gran-faculdade\">Por que a Gran Faculdade?<\/h2>\n\n\n\n<p>Para Juliana, a escolha da Gran Faculdade foi estrat\u00e9gica: por ser a base de todas as leis, o teor de conhecimento \u00e9 elevado, ainda mais levando em conta que estudo para concurso\u201d, comenta, refor\u00e7ando o n\u00edvel de profundidade da p\u00f3s-gradua\u00e7\u00e3o em Direito Constitucional. <\/p>\n\n\n\n<p>A estrutura de ensino e o acolhimento desde os primeiros contatos tamb\u00e9m fizeram a diferen\u00e7a: \u201cDa recep\u00e7\u00e3o, das aulas aos professores\u201d, diz ela, destacando a qualidade do corpo docente. Outro ponto decisivo foi o investimento acess\u00edvel:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>O pre\u00e7o em conta pesou positivamente na decis\u00e3o. Um curso completo e com valor justo \u00e9 um diferencial importante<\/p>\n<\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-trajetoria-profissional\">Trajet\u00f3ria Profissional<\/h2>\n\n\n\n<p>A rotina de Juliana vai muito al\u00e9m dos estudos. Ela atua como advogada, trabalha na \u00e1rea de marketing e ainda encontra tempo para se dedicar aos concursos p\u00fablicos. Apesar dos m\u00faltiplos pap\u00e9is, \u00e9 nos estudos que ela concentra sua energia maior atualmente: <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Estudo na maior parte da semana de 4 a 5 horas, de segunda a s\u00e1bado. A advocacia e o marketing s\u00e3o o segundo plano, porque a\u00ed ajusto na semana conforme a demanda.<\/p>\n<\/blockquote>\n\n\n\n<p>Juliana tamb\u00e9m j\u00e1 vislumbra novas possibilidades profissionais a partir da p\u00f3s-gradua\u00e7\u00e3o. \u201cDar aula futuramente, fazer uns resumos para vender\u201d, revela, mostrando como o curso est\u00e1 abrindo caminhos para novas iniciativas e formas de atua\u00e7\u00e3o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-vida-pessoal\">Vida Pessoal<\/h2>\n\n\n\n<p>Mesmo com uma agenda cheia, Juliana valoriza o equil\u00edbrio e encontra tempo para se cuidar e se divertir. Seus passatempos favoritos incluem aprender idiomas com o Duolingo, ler livros, assistir s\u00e9ries e se exercitar. Ela tamb\u00e9m cultiva h\u00e1bitos que alimentam sua criatividade e bem-estar: <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Gosto de fazer muscula\u00e7\u00e3o, correr, ouvir podcasts, cantar e ouvir m\u00fasica.<\/p>\n<\/blockquote>\n\n\n\n<p>Entre seus livros preferidos est\u00e3o t\u00edtulos que inspiram crescimento pessoal e financeiro: Impar\u00e1vel, &#8220;O Segredo&#8221; e &#8220;Pai Rico, Pai Pobre&#8221;. E, claro, n\u00e3o poderiam faltar detalhes leves e curiosos sobre sua personalidade: \u201cEu crio uns mnem\u00f4nicos estudando e alguns s\u00e3o engra\u00e7ados\u201d, confessa, com bom humor. E quando o assunto \u00e9 sorvete, ela n\u00e3o tem d\u00favidas: \u201cCreme \u00e9 o meu sabor favorito!\u201d<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-dias-e-perspectivas-para-o-futuro\">Dias e Perspectivas para o futuro<\/h2>\n\n\n\n<p>Apesar dos desafios, Juliana encara a vida com perseveran\u00e7a. Quando perguntada se pensa em desistir, a resposta \u00e9 firme: \u201cN\u00e3o, mesmo com problemas, porque a vida n\u00e3o para, eu n\u00e3o costumo desistir.\u201d Para ela, cada dia \u00e9 uma oportunidade de avan\u00e7ar, aprender e construir seus sonhos.<\/p>\n\n\n\n<p>A p\u00f3s-gradua\u00e7\u00e3o da Gran Faculdade tem sido, segundo suas palavras, \u201cmuito proveitosa\u201d, e est\u00e1 contribuindo n\u00e3o s\u00f3 com sua forma\u00e7\u00e3o t\u00e9cnica, mas tamb\u00e9m com seu amadurecimento pessoal. \u201cEla pode e est\u00e1 ampliando meu crescimento, e n\u00e3o s\u00f3 o profissional\u201d, afirma.<\/p>\n\n\n\n<p>E, como dizia Dory, personagem que inspira sua mentalidade: \u201cContinue a nadar.\u201d Juliana segue em frente, estudando com garra, criando seus pr\u00f3prios m\u00e9todos e deixando sua marca \u2014 dentro e fora da sala de aula.<\/p>\n\n\n\n<div class=\"wp-block-group has-background\" style=\"background-color:#8dd2fc7a\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p><strong>Outras not\u00edcias em destaque:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/faculdade.grancursosonline.com.br\/blog\/pos-graduacao-em-direito-constitucional\/\" target=\"_blank\" rel=\"noreferrer noopener\">P\u00f3s-Gradua\u00e7\u00e3o em Direito Constitucional: conhe\u00e7a o curso!<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/faculdade.grancursosonline.com.br\/blog\/pos-graduacao-em-direito\/\" target=\"_blank\" rel=\"noreferrer noopener\">P\u00f3s-Gradua\u00e7\u00e3o em Direito: conhe\u00e7a o melhor curso para voc\u00ea!<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/faculdade.grancursosonline.com.br\/blog\/direito-para-concurseiros-melhores-areas\/\" target=\"_blank\" rel=\"noreferrer noopener\">Direito para concurseiros: quais s\u00e3o as melhores \u00e1reas?<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/faculdade.grancursosonline.com.br\/blog\/pos-graduacao-em-direito-administrativo\/\" target=\"_blank\" rel=\"noreferrer noopener\">P\u00f3s-Gradua\u00e7\u00e3o em Direito Administrativo: por que fazer? VEJA!<\/a><\/li>\n<\/ul>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-conheca-os-cursos-da-gran-faculdade\">Conhe\u00e7a os cursos da Gran Faculdade!<\/h2>\n\n\n\n<p>Na <a href=\"https:\/\/faculdade.grancursosonline.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">Gran Faculdade<\/a>, voc\u00ea encontra diversas op\u00e7\u00f5es para sua forma\u00e7\u00e3o, desde cursos de <a href=\"https:\/\/faculdade.grancursosonline.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">gradua\u00e7\u00e3o<\/a> at\u00e9 <a href=\"https:\/\/pos.grancursosonline.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">especializa\u00e7\u00f5es<\/a> e <a href=\"https:\/\/pos.grancursosonline.com.br\/mba\" target=\"_blank\" rel=\"noreferrer noopener\">MBAs<\/a>, com a flexibilidade e qualidade que voc\u00ea precisa para avan\u00e7ar na sua carreira.<\/p>\n\n\n\n<p>Nossos cursos de <a href=\"https:\/\/faculdade.grancursosonline.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">gradua\u00e7\u00e3o<\/a> e <a href=\"https:\/\/pos.grancursosonline.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">p\u00f3s-gradua\u00e7\u00e3o EAD<\/a> s\u00e3o 100% online, mas tamb\u00e9m oferecemos op\u00e7\u00f5es de <a href=\"https:\/\/presencial.grancursosonline.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">cursos presenciais no Campus Curitiba<\/a>, permitindo que voc\u00ea estude de forma pr\u00e1tica e no seu ritmo e do seu jeito, otimizando tamb\u00e9m a prepara\u00e7\u00e3o para concursos p\u00fablicos. Eles oferecem uma base s\u00f3lida para sua atua\u00e7\u00e3o profissional e te ajudam a se destacar ainda mais no mercado.<\/p>\n\n\n\n<p>S\u00e3o v\u00e1rias op\u00e7\u00f5es de cursos nas \u00e1reas de Gest\u00e3o, Educa\u00e7\u00e3o, Direito, Policial, Tecnologia e Engenharia. Aqui, voc\u00ea estuda em uma institui\u00e7\u00e3o reconhecida pelo MEC com nota m\u00e1xima, aproveitando mensalidades acess\u00edveis e ajustadas \u00e0 sua rotina.<\/p>\n\n\n\n<p>N\u00e3o perca a chance de transformar sua vida acad\u00eamica e profissional! Confira nossos cursos, fa\u00e7a sua matr\u00edcula e comece hoje mesmo sua jornada com o Gran Faculdade:<\/p>\n\n\n\n<p class=\"has-text-align-center\"><a href=\"https:\/\/faculdade.grancursosonline.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">Conhe\u00e7a os cursos da Gran Faculdade<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-vem-pra-gran-faculdade\">Vem pra Gran Faculdade!<\/h2>\n\n\n\n<p>A Gran Faculdade vem mudando a vida de milhares de pessoas por meio de cursos \u00e0 dist\u00e2ncia de <a href=\"https:\/\/faculdade.grancursosonline.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">gradua\u00e7\u00e3o<\/a>, <a href=\"https:\/\/pos.grancursosonline.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">p\u00f3s-gradua\u00e7\u00e3o<\/a> e <a href=\"https:\/\/pos.grancursosonline.com.br\/mba\" target=\"_blank\" rel=\"noreferrer noopener\">MBA<\/a>. Seja no digital ou em nosso <a href=\"https:\/\/presencial.grancursosonline.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">Campus Presencial em Curitiba<\/a>, a nossa miss\u00e3o \u00e9 transformar a educa\u00e7\u00e3o superior.<\/p>\n\n\n\n<p>Como parte de Sistema Gran de Ensino, que \u00e9 reconhecido como marca aprovadora h\u00e1 mais de 10 anos, constru\u00edmos uma renomada reputa\u00e7\u00e3o na \u00e1rea de educa\u00e7\u00e3o.<\/p>\n\n\n\n<p>Veja algumas de nossas conquistas:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Reconhecido pela Amazon como um dos projetos mais relevantes do mundo na \u00e1rea de Tecnologia e Educa\u00e7\u00e3o;<\/li>\n\n\n\n<li>Foi eleito pelo Project Management Institute (PMI), um dos 50 Projetos Mais Influentes do mundo;<\/li>\n\n\n\n<li>Somos o site de educa\u00e7\u00e3o mais acessado do Brasil;<\/li>\n\n\n\n<li>Somos avaliados com a nota m\u00e1xima pelo MEC;<\/li>\n\n\n\n<li>Aqui o semestre come\u00e7a quando quiser: entrada imediata e cont\u00ednua!<\/li>\n\n\n\n<li>Melhores pre\u00e7os do mercado;<\/li>\n\n\n\n<li>Mais de 500 mil alunos pagantes e mais de 1000 funcion\u00e1rios;<\/li>\n\n\n\n<li>Diversas ferramentas de estudo: PDFs, audiobooks, mapas mentais, videoaulas, quest\u00f5es, gerenciador de estudos e muito mais!<\/li>\n\n\n\n<li>Professores experientes e capacitados;<\/li>\n\n\n\n<li>Acesso imediato e 100% online.<\/li>\n<\/ul>\n\n\n\n<p class=\"has-text-align-center has-text-align-center\"><strong><a href=\"https:\/\/faculdade.grancursosonline.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">Quero ser aluno da Gran Faculdade!<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apesar da rotina intensa e multifacetada, Juliana Gon\u00e7alves encontrou na P\u00f3s-gradua\u00e7\u00e3o em Direito Constitucional da Gran Faculdade n\u00e3o apenas uma aliada para o crescimento profissional, mas tamb\u00e9m um impulso para o desenvolvimento pessoal. Advogada, profissional de marketing e estudante dedicada, ela compartilhou sua experi\u00eancia com a institui\u00e7\u00e3o e revelou como tem conciliado seus objetivos com&hellip;<\/p>\n","protected":false},"author":486,"featured_media":79752965,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[220347,209229,2],"tags":[],"class_list":["post-79752964","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-depoimentos","category-pos-graduacao","category-ultimas-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Conhe\u00e7a a hist\u00f3ria de Juliana Gon\u00e7alves, aluna da gran p\u00f3s!<\/title>\n<meta name=\"description\" content=\"Conhe\u00e7a Juliana Gon\u00e7alves, aluna da p\u00f3s em Direito Constitucional da Gran Faculdade, que equilibra advocacia e estudos com foco no crescimento pessoal e profissional\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-juliana-goncalves-pos-graduacao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conhe\u00e7a a hist\u00f3ria de Juliana Gon\u00e7alves, aluna da gran p\u00f3s!\" \/>\n<meta property=\"og:description\" content=\"Conhe\u00e7a Juliana Gon\u00e7alves, aluna da p\u00f3s em Direito Constitucional da Gran Faculdade, que equilibra advocacia e estudos com foco no crescimento pessoal e profissional\" \/>\n<meta property=\"og:url\" content=\"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-juliana-goncalves-pos-graduacao\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Gran Faculdade\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/grancursosonline\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-09T21:10:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-25T16:23:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog-es-static.infra.grancursosonline.com.br\/wp-content\/uploads\/2025\/04\/09094543\/depoimento-juliana-goncalves-pos-graduacao-social.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"511\" \/>\n\t<meta property=\"og:image:height\" content=\"311\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Equipe Gran\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@gran_online\" \/>\n<meta name=\"twitter:site\" content=\"@gran_online\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipe Gran\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-juliana-goncalves-pos-graduacao\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-juliana-goncalves-pos-graduacao\/\"},\"author\":{\"name\":\"Equipe Gran\",\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/#\/schema\/person\/c05f350f8ea43a7138aaffc6a87bc5e0\"},\"headline\":\"Conhe\u00e7a a hist\u00f3ria de Juliana Gon\u00e7alves, aluna da gran p\u00f3s!\",\"datePublished\":\"2025-04-09T21:10:44+00:00\",\"dateModified\":\"2025-04-25T16:23:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-juliana-goncalves-pos-graduacao\/\"},\"wordCount\":652,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-juliana-goncalves-pos-graduacao\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blog-es-static.infra.grancursosonline.com.br\/wp-content\/uploads\/2025\/04\/09094457\/depoimento-juliana-goncalves-pos-graduacao.jpg\",\"articleSection\":[\"Eu Sou Gran\",\"P\u00f3s-Gradua\u00e7\u00e3o Gran Faculdade\",\"\u00daltimas Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-juliana-goncalves-pos-graduacao\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-juliana-goncalves-pos-graduacao\/\",\"url\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-juliana-goncalves-pos-graduacao\/\",\"name\":\"Conhe\u00e7a a hist\u00f3ria de Juliana Gon\u00e7alves, aluna da gran p\u00f3s!\",\"isPartOf\":{\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-juliana-goncalves-pos-graduacao\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-juliana-goncalves-pos-graduacao\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blog-es-static.infra.grancursosonline.com.br\/wp-content\/uploads\/2025\/04\/09094457\/depoimento-juliana-goncalves-pos-graduacao.jpg\",\"datePublished\":\"2025-04-09T21:10:44+00:00\",\"dateModified\":\"2025-04-25T16:23:09+00:00\",\"description\":\"Conhe\u00e7a Juliana Gon\u00e7alves, aluna da p\u00f3s em Direito Constitucional da Gran Faculdade, que equilibra advocacia e estudos com foco no crescimento pessoal e profissional\",\"breadcrumb\":{\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-juliana-goncalves-pos-graduacao\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-juliana-goncalves-pos-graduacao\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-juliana-goncalves-pos-graduacao\/#primaryimage\",\"url\":\"https:\/\/blog-es-static.infra.grancursosonline.com.br\/wp-content\/uploads\/2025\/04\/09094457\/depoimento-juliana-goncalves-pos-graduacao.jpg\",\"contentUrl\":\"https:\/\/blog-es-static.infra.grancursosonline.com.br\/wp-content\/uploads\/2025\/04\/09094457\/depoimento-juliana-goncalves-pos-graduacao.jpg\",\"width\":1001,\"height\":601,\"caption\":\"Conhe\u00e7a a hist\u00f3ria de Juliana Gon\u00e7alves, aluna da Gran P\u00f3s!\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-juliana-goncalves-pos-graduacao\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eu Sou Gran\",\"item\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimentos\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Conhe\u00e7a a hist\u00f3ria de Juliana Gon\u00e7alves, aluna da gran p\u00f3s!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/#website\",\"url\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/\",\"name\":\"Blog Gran Faculdade\",\"description\":\"Tudo sobre ensino superior, p\u00f3s-gradua\u00e7\u00e3o, enem e carreira.\",\"publisher\":{\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/#organization\",\"name\":\"Gran Cursos Online\",\"url\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/blog-es-static.infra.grancursosonline.com.br\/wp-content\/uploads\/2019\/08\/03123934\/logo.png\",\"contentUrl\":\"https:\/\/blog-es-static.infra.grancursosonline.com.br\/wp-content\/uploads\/2019\/08\/03123934\/logo.png\",\"width\":300,\"height\":57,\"caption\":\"Gran Cursos Online\"},\"image\":{\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/grancursosonline\/\",\"https:\/\/x.com\/gran_online\",\"https:\/\/www.instagram.com\/grancursosonline\/\",\"https:\/\/www.youtube.com\/user\/grancursostv\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/#\/schema\/person\/c05f350f8ea43a7138aaffc6a87bc5e0\",\"name\":\"Equipe Gran\",\"sameAs\":[\"http:\/\/www.grancursosonline.com.br\"],\"url\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/author\/hugo-oliveira\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Conhe\u00e7a a hist\u00f3ria de Juliana Gon\u00e7alves, aluna da gran p\u00f3s!","description":"Conhe\u00e7a Juliana Gon\u00e7alves, aluna da p\u00f3s em Direito Constitucional da Gran Faculdade, que equilibra advocacia e estudos com foco no crescimento pessoal e profissional","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-juliana-goncalves-pos-graduacao\/","og_locale":"pt_BR","og_type":"article","og_title":"Conhe\u00e7a a hist\u00f3ria de Juliana Gon\u00e7alves, aluna da gran p\u00f3s!","og_description":"Conhe\u00e7a Juliana Gon\u00e7alves, aluna da p\u00f3s em Direito Constitucional da Gran Faculdade, que equilibra advocacia e estudos com foco no crescimento pessoal e profissional","og_url":"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-juliana-goncalves-pos-graduacao\/","og_site_name":"Blog Gran Faculdade","article_publisher":"https:\/\/www.facebook.com\/grancursosonline\/","article_published_time":"2025-04-09T21:10:44+00:00","article_modified_time":"2025-04-25T16:23:09+00:00","og_image":[{"width":511,"height":311,"url":"https:\/\/blog-es-static.infra.grancursosonline.com.br\/wp-content\/uploads\/2025\/04\/09094543\/depoimento-juliana-goncalves-pos-graduacao-social.jpg","type":"image\/jpeg"}],"author":"Equipe Gran","twitter_card":"summary_large_image","twitter_creator":"@gran_online","twitter_site":"@gran_online","twitter_misc":{"Written by":"Equipe Gran","Est. reading time":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-juliana-goncalves-pos-graduacao\/#article","isPartOf":{"@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-juliana-goncalves-pos-graduacao\/"},"author":{"name":"Equipe Gran","@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/#\/schema\/person\/c05f350f8ea43a7138aaffc6a87bc5e0"},"headline":"Conhe\u00e7a a hist\u00f3ria de Juliana Gon\u00e7alves, aluna da gran p\u00f3s!","datePublished":"2025-04-09T21:10:44+00:00","dateModified":"2025-04-25T16:23:09+00:00","mainEntityOfPage":{"@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-juliana-goncalves-pos-graduacao\/"},"wordCount":652,"commentCount":0,"publisher":{"@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-juliana-goncalves-pos-graduacao\/#primaryimage"},"thumbnailUrl":"https:\/\/blog-es-static.infra.grancursosonline.com.br\/wp-content\/uploads\/2025\/04\/09094457\/depoimento-juliana-goncalves-pos-graduacao.jpg","articleSection":["Eu Sou Gran","P\u00f3s-Gradua\u00e7\u00e3o Gran Faculdade","\u00daltimas Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-juliana-goncalves-pos-graduacao\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-juliana-goncalves-pos-graduacao\/","url":"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-juliana-goncalves-pos-graduacao\/","name":"Conhe\u00e7a a hist\u00f3ria de Juliana Gon\u00e7alves, aluna da gran p\u00f3s!","isPartOf":{"@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-juliana-goncalves-pos-graduacao\/#primaryimage"},"image":{"@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-juliana-goncalves-pos-graduacao\/#primaryimage"},"thumbnailUrl":"https:\/\/blog-es-static.infra.grancursosonline.com.br\/wp-content\/uploads\/2025\/04\/09094457\/depoimento-juliana-goncalves-pos-graduacao.jpg","datePublished":"2025-04-09T21:10:44+00:00","dateModified":"2025-04-25T16:23:09+00:00","description":"Conhe\u00e7a Juliana Gon\u00e7alves, aluna da p\u00f3s em Direito Constitucional da Gran Faculdade, que equilibra advocacia e estudos com foco no crescimento pessoal e profissional","breadcrumb":{"@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-juliana-goncalves-pos-graduacao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-juliana-goncalves-pos-graduacao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-juliana-goncalves-pos-graduacao\/#primaryimage","url":"https:\/\/blog-es-static.infra.grancursosonline.com.br\/wp-content\/uploads\/2025\/04\/09094457\/depoimento-juliana-goncalves-pos-graduacao.jpg","contentUrl":"https:\/\/blog-es-static.infra.grancursosonline.com.br\/wp-content\/uploads\/2025\/04\/09094457\/depoimento-juliana-goncalves-pos-graduacao.jpg","width":1001,"height":601,"caption":"Conhe\u00e7a a hist\u00f3ria de Juliana Gon\u00e7alves, aluna da Gran P\u00f3s!"},{"@type":"BreadcrumbList","@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-juliana-goncalves-pos-graduacao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/faculdade.grancursosonline.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Eu Sou Gran","item":"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimentos\/"},{"@type":"ListItem","position":3,"name":"Conhe\u00e7a a hist\u00f3ria de Juliana Gon\u00e7alves, aluna da gran p\u00f3s!"}]},{"@type":"WebSite","@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/#website","url":"https:\/\/faculdade.grancursosonline.com.br\/blog\/","name":"Blog Gran Faculdade","description":"Tudo sobre ensino superior, p\u00f3s-gradua\u00e7\u00e3o, enem e carreira.","publisher":{"@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/faculdade.grancursosonline.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/#organization","name":"Gran Cursos Online","url":"https:\/\/faculdade.grancursosonline.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/blog-es-static.infra.grancursosonline.com.br\/wp-content\/uploads\/2019\/08\/03123934\/logo.png","contentUrl":"https:\/\/blog-es-static.infra.grancursosonline.com.br\/wp-content\/uploads\/2019\/08\/03123934\/logo.png","width":300,"height":57,"caption":"Gran Cursos Online"},"image":{"@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/grancursosonline\/","https:\/\/x.com\/gran_online","https:\/\/www.instagram.com\/grancursosonline\/","https:\/\/www.youtube.com\/user\/grancursostv"]},{"@type":"Person","@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/#\/schema\/person\/c05f350f8ea43a7138aaffc6a87bc5e0","name":"Equipe Gran","sameAs":["http:\/\/www.grancursosonline.com.br"],"url":"https:\/\/faculdade.grancursosonline.com.br\/blog\/author\/hugo-oliveira\/"}]}},"_links":{"self":[{"href":"https:\/\/faculdade.grancursosonline.com.br\/blog\/wp-json\/wp\/v2\/posts\/79752964","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/faculdade.grancursosonline.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/faculdade.grancursosonline.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/faculdade.grancursosonline.com.br\/blog\/wp-json\/wp\/v2\/users\/486"}],"replies":[{"embeddable":true,"href":"https:\/\/faculdade.grancursosonline.com.br\/blog\/wp-json\/wp\/v2\/comments?post=79752964"}],"version-history":[{"count":4,"href":"https:\/\/faculdade.grancursosonline.com.br\/blog\/wp-json\/wp\/v2\/posts\/79752964\/revisions"}],"predecessor-version":[{"id":79753481,"href":"https:\/\/faculdade.grancursosonline.com.br\/blog\/wp-json\/wp\/v2\/posts\/79752964\/revisions\/79753481"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/faculdade.grancursosonline.com.br\/blog\/wp-json\/wp\/v2\/media\/79752965"}],"wp:attachment":[{"href":"https:\/\/faculdade.grancursosonline.com.br\/blog\/wp-json\/wp\/v2\/media?parent=79752964"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/faculdade.grancursosonline.com.br\/blog\/wp-json\/wp\/v2\/categories?post=79752964"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/faculdade.grancursosonline.com.br\/blog\/wp-json\/wp\/v2\/tags?post=79752964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}