{"id":79753210,"date":"2025-04-16T17:37:38","date_gmt":"2025-04-16T20:37:38","guid":{"rendered":"https:\/\/faculdade.grancursosonline.com.br\/blog\/?p=79753210"},"modified":"2025-04-25T13:21:23","modified_gmt":"2025-04-25T16:21:23","slug":"depoimento-uyhara-barreira-pos-graduacao","status":"publish","type":"post","link":"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-uyhara-barreira-pos-graduacao\/","title":{"rendered":"Conhe\u00e7a a hist\u00f3ria de Uyhara Barreira, aluna Gran P\u00f3s"},"content":{"rendered":"\n<p>Em busca de desenvolvimento profissional e equil\u00edbrio entre vida pessoal, trabalho e estudos, Uyhara Barreira escolheu a Gran Faculdade como parceira na realiza\u00e7\u00e3o de um grande passo da sua trajet\u00f3ria: a p\u00f3s-gradua\u00e7\u00e3o em Direito Civil e Processo Civil. Ela compartilhou com a gente sua experi\u00eancia com o curso, revelando como a modalidade online, a qualidade dos professores e a organiza\u00e7\u00e3o pessoal foram fundamentais para manter o ritmo e o entusiasmo com os estudos.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/whatsapp.com\/channel\/0029VaG1sChI7Be7PNndhL43\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/blog-es-static.infra.grancursosonline.com.br\/wp-content\/uploads\/2025\/09\/09112354\/banner-wp-600x142-80.webp\" alt=\"Acesse o canal do WhatsApp da Gran Faculdade\" class=\"wp-image-79751904\"\/><\/a><\/figure>\n<\/div><\/div>\n<\/div>\n\n\n\n<p>Acompanhe o artigo para saber mais ou navegue pelo \u00edndice:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"#gran\">Por que a Gran Faculdade?<\/a><\/li>\n\n\n\n<li><a href=\"#profissional\">Trajet\u00f3ria Profissional<\/a><\/li>\n\n\n\n<li><a href=\"#pessoal\">Vida Pessoal<\/a><\/li>\n\n\n\n<li><a href=\"#dicas\">Dicas e Perspectivas para o futuro<\/a><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-guia-da-carreira-juridica-conheca-todas-as-oportunidades-na-area\">Guia da Carreira Jur\u00eddica: conhe\u00e7a TODAS as oportunidades na \u00e1rea!<\/h2>\n\n\n\n<p>A carreira jur\u00eddica \u00e9 fundamental para a manuten\u00e7\u00e3o da ordem e da justi\u00e7a na sociedade, assegurando que as leis sejam aplicadas de maneira eficaz e equitativa, protegendo direitos individuais e resolvendo conflitos. <\/p>\n\n\n\n<p>Desse modo, o setor n\u00e3o \u00e9 apenas uma oportunidade de crescimento profissional, mas tamb\u00e9m um compromisso com a \u00e9tica, a justi\u00e7a, o servi\u00e7o p\u00fablico e os cidad\u00e3os. <\/p>\n\n\n\n<p>Neste guia, exploraremos o que \u00e9 a \u00e1rea Jur\u00eddica, as raz\u00f5es para seguir uma carreira neste campo, as principais carreira para atua\u00e7\u00e3o e os primeiros passos para come\u00e7ar a sua jornada:<\/p>\n\n\n\n<script charset=\"utf-8\" type=\"text\/javascript\" src=\"\/\/js.hsforms.net\/forms\/embed\/v2.js\"><\/script>\n<script>\n  hbspt.forms.create({\n    region: \"na1\",\n    portalId: \"302036\",\n    formId: \"beba25ff-9c07-4d74-952b-42234f4d6d20\"\n  });\n<\/script>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-por-que-a-gran-faculdade\">Por que a Gran Faculdade?<\/h2>\n\n\n\n<p>A decis\u00e3o por estudar na Gran Faculdade veio da combina\u00e7\u00e3o de dois fatores decisivos para Uyhara: a praticidade das aulas online e a qualidade dos professores:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Ser online e com professores que gosto fez toda a diferen\u00e7a. A praticidade das aulas dispon\u00edveis na plataforma torna o processo mais tranquilo, especialmente por conta da flexibilidade de hor\u00e1rios e do prazo para conclus\u00e3o do curso.<\/p>\n<\/blockquote>\n\n\n\n<p>Ela destaca ainda a plataforma como um diferencial importante. Com conte\u00fado sempre acess\u00edvel, Uyhara conseguiu adaptar a rotina de estudos \u00e0 sua realidade e seguir um cronograma feito sob medida para seu dia a dia.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-trajetoria-profissional\">Trajet\u00f3ria Profissional<\/h2>\n\n\n\n<p>Com o foco claro em crescer na carreira jur\u00eddica, Uyhara v\u00ea a p\u00f3s-gradua\u00e7\u00e3o como um passo fundamental para a ascens\u00e3o profissional. Embora ainda n\u00e3o tenha experimentado mudan\u00e7as pr\u00e1ticas no trabalho at\u00e9 o momento, ela est\u00e1 certa de que o conhecimento adquirido ser\u00e1 decisivo para alcan\u00e7ar novas conquistas. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Com a conclus\u00e3o da p\u00f3s, terei mais conhecimento para aplicar ao meu trabalho e um consequente aumento salarial.<\/p>\n<\/blockquote>\n\n\n\n<p>Sua rotina \u00e9 intensa: faz outro curso pela manh\u00e3, trabalha \u00e0 tarde e reserva a noite para a p\u00f3s-gradua\u00e7\u00e3o. A organiza\u00e7\u00e3o \u00e9 essencial, e ela utilizou os pr\u00f3prios recursos da plataforma da Gran Faculdade para montar um cronograma que se ajustasse ao seu ritmo de vida.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-vida-pessoal\">Vida Pessoal<\/h2>\n\n\n\n<p>Apesar da rotina cheia, Uyhara n\u00e3o abre m\u00e3o dos momentos de lazer. Para ela, manter esse equil\u00edbrio \u00e9 o que garante energia e bem-estar para seguir firme nos estudos e no trabalho.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Meu lazer favorito \u00e9 sair pra um caf\u00e9 ou um lanche com minha fam\u00edlia e minhas amigas. Esse tempo com eles descansa a minha mente e me faz muito bem!.<\/p>\n<\/blockquote>\n\n\n\n<p>Sua hist\u00f3ria mostra que \u00e9 poss\u00edvel conciliar diversas responsabilidades com a vida acad\u00eamica, desde que haja planejamento e autoconhecimento.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-dias-e-perspectivas-para-o-futuro\">Dias e Perspectivas para o futuro<\/h2>\n\n\n\n<p>Hoje, Uyhara vive um momento de dedica\u00e7\u00e3o e foco, mas tamb\u00e9m de constru\u00e7\u00e3o. Cada aula, cada conte\u00fado estudado representa um degrau a mais em dire\u00e7\u00e3o ao futuro que ela deseja. E mesmo com desafios, ela deixa uma mensagem encorajadora para quem est\u00e1 come\u00e7ando:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Estabele\u00e7a uma rotina sustent\u00e1vel e permane\u00e7a firme nela. No entanto, caso n\u00e3o seja poss\u00edvel, reprograme suas expectativas e realinhe o curso. Vai dar certo no final!<\/p>\n<\/blockquote>\n\n\n\n<p>Com determina\u00e7\u00e3o, organiza\u00e7\u00e3o e o apoio da Gran Faculdade, Uyhara segue transformando conhecimento em oportunidade, inspirando outros profissionais a fazerem o mesmo.<\/p>\n\n\n\n<div class=\"wp-block-group has-background\" style=\"background-color:#8dd2fc7a\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p><strong>Outras not\u00edcias em destaque:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/faculdade.grancursosonline.com.br\/blog\/direito-ead\/\" target=\"_blank\" rel=\"noreferrer noopener\">Existe curso de Direito EAD? Entenda tudo!<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/faculdade.grancursosonline.com.br\/blog\/me-formei-em-direito-e-agora\/\" target=\"_blank\" rel=\"noreferrer noopener\">Me formei em Direito e agora? OAB, p\u00f3s ou concurso p\u00fablico?<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/blog.grancursosonline.com.br\/direito-para-concursos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Direito para Concursos: guia de temas jur\u00eddicos fundamentais<\/a><\/li>\n<\/ul>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-conheca-os-cursos-da-gran-faculdade\">Conhe\u00e7a os cursos da Gran Faculdade!<\/h2>\n\n\n\n<p>Na <a href=\"https:\/\/faculdade.grancursosonline.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">Gran Faculdade<\/a>, voc\u00ea encontra diversas op\u00e7\u00f5es para sua forma\u00e7\u00e3o, desde cursos de <a href=\"https:\/\/faculdade.grancursosonline.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">gradua\u00e7\u00e3o<\/a> at\u00e9 <a href=\"https:\/\/pos.grancursosonline.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">especializa\u00e7\u00f5es<\/a> e <a href=\"https:\/\/pos.grancursosonline.com.br\/mba\" target=\"_blank\" rel=\"noreferrer noopener\">MBAs<\/a>, com a flexibilidade e qualidade que voc\u00ea precisa para avan\u00e7ar na sua carreira.<\/p>\n\n\n\n<p>Nossos cursos de <a href=\"https:\/\/faculdade.grancursosonline.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">gradua\u00e7\u00e3o<\/a> e <a href=\"https:\/\/pos.grancursosonline.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">p\u00f3s-gradua\u00e7\u00e3o EAD<\/a> s\u00e3o 100% online, mas tamb\u00e9m oferecemos op\u00e7\u00f5es de <a href=\"https:\/\/presencial.grancursosonline.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">cursos presenciais no Campus Curitiba<\/a>, permitindo que voc\u00ea estude de forma pr\u00e1tica e no seu ritmo e do seu jeito, otimizando tamb\u00e9m a prepara\u00e7\u00e3o para concursos p\u00fablicos. Eles oferecem uma base s\u00f3lida para sua atua\u00e7\u00e3o profissional e te ajudam a se destacar ainda mais no mercado.<\/p>\n\n\n\n<p>S\u00e3o v\u00e1rias op\u00e7\u00f5es de cursos nas \u00e1reas de Gest\u00e3o, Educa\u00e7\u00e3o, Direito, Policial, Tecnologia e Engenharia. Aqui, voc\u00ea estuda em uma institui\u00e7\u00e3o reconhecida pelo MEC com nota m\u00e1xima, aproveitando mensalidades acess\u00edveis e ajustadas \u00e0 sua rotina.<\/p>\n\n\n\n<p>N\u00e3o perca a chance de transformar sua vida acad\u00eamica e profissional! Confira nossos cursos, fa\u00e7a sua matr\u00edcula e comece hoje mesmo sua jornada com o Gran Faculdade:<\/p>\n\n\n\n<p class=\"has-text-align-center\"><a href=\"https:\/\/faculdade.grancursosonline.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">Conhe\u00e7a os cursos da Gran Faculdade<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-vem-pra-gran-faculdade\">Vem pra Gran Faculdade!<\/h2>\n\n\n\n<p>A Gran Faculdade vem mudando a vida de milhares de pessoas por meio de cursos \u00e0 dist\u00e2ncia de <a href=\"https:\/\/faculdade.grancursosonline.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">gradua\u00e7\u00e3o<\/a>, <a href=\"https:\/\/pos.grancursosonline.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">p\u00f3s-gradua\u00e7\u00e3o<\/a> e <a href=\"https:\/\/pos.grancursosonline.com.br\/mba\" target=\"_blank\" rel=\"noreferrer noopener\">MBA<\/a>. Seja no digital ou em nosso <a href=\"https:\/\/presencial.grancursosonline.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">Campus Presencial em Curitiba<\/a>, a nossa miss\u00e3o \u00e9 transformar a educa\u00e7\u00e3o superior.<\/p>\n\n\n\n<p>Como parte de Sistema Gran de Ensino, que \u00e9 reconhecido como marca aprovadora h\u00e1 mais de 10 anos, constru\u00edmos uma renomada reputa\u00e7\u00e3o na \u00e1rea de educa\u00e7\u00e3o.<\/p>\n\n\n\n<p>Veja algumas de nossas conquistas:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Reconhecido pela Amazon como um dos projetos mais relevantes do mundo na \u00e1rea de Tecnologia e Educa\u00e7\u00e3o;<\/li>\n\n\n\n<li>Foi eleito pelo Project Management Institute (PMI), um dos 50 Projetos Mais Influentes do mundo;<\/li>\n\n\n\n<li>Somos o site de educa\u00e7\u00e3o mais acessado do Brasil;<\/li>\n\n\n\n<li>Somos avaliados com a nota m\u00e1xima pelo MEC;<\/li>\n\n\n\n<li>Aqui o semestre come\u00e7a quando quiser: entrada imediata e cont\u00ednua!<\/li>\n\n\n\n<li>Melhores pre\u00e7os do mercado;<\/li>\n\n\n\n<li>Mais de 500 mil alunos pagantes e mais de 1000 funcion\u00e1rios;<\/li>\n\n\n\n<li>Diversas ferramentas de estudo: PDFs, audiobooks, mapas mentais, videoaulas, quest\u00f5es, gerenciador de estudos e muito mais!<\/li>\n\n\n\n<li>Professores experientes e capacitados;<\/li>\n\n\n\n<li>Acesso imediato e 100% online.<\/li>\n<\/ul>\n\n\n\n<p class=\"has-text-align-center has-text-align-center\"><strong><a href=\"https:\/\/faculdade.grancursosonline.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">Quero ser aluno da Gran Faculdade!<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em busca de desenvolvimento profissional e equil\u00edbrio entre vida pessoal, trabalho e estudos, Uyhara Barreira escolheu a Gran Faculdade como parceira na realiza\u00e7\u00e3o de um grande passo da sua trajet\u00f3ria: a p\u00f3s-gradua\u00e7\u00e3o em Direito Civil e Processo Civil. Ela compartilhou com a gente sua experi\u00eancia com o curso, revelando como a modalidade online, a qualidade&hellip;<\/p>\n","protected":false},"author":486,"featured_media":79753212,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[220347,209229,2],"tags":[],"class_list":["post-79753210","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-depoimentos","category-pos-graduacao","category-ultimas-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Conhe\u00e7a a hist\u00f3ria de Uyhara Barreira, aluna Gran P\u00f3s<\/title>\n<meta name=\"description\" content=\"Uyhara Barreira revela como a flexibilidade da p\u00f3s-gradua\u00e7\u00e3o online em Direito Civil e Processo Civil da Gran Faculdade foi essencial para equilibrar sua rotina e carreira.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-uyhara-barreira-pos-graduacao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conhe\u00e7a a hist\u00f3ria de Uyhara Barreira, aluna Gran P\u00f3s\" \/>\n<meta property=\"og:description\" content=\"Uyhara Barreira revela como a flexibilidade da p\u00f3s-gradua\u00e7\u00e3o online em Direito Civil e Processo Civil da Gran Faculdade foi essencial para equilibrar sua rotina e carreira.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-uyhara-barreira-pos-graduacao\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Gran Faculdade\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/grancursosonline\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-16T20:37:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-25T16:21:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog-es-static.infra.grancursosonline.com.br\/wp-content\/uploads\/2025\/04\/16105534\/depoimento-uyhara-barreira-pos-graduacao.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"511\" \/>\n\t<meta property=\"og:image:height\" content=\"311\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Equipe Gran\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@gran_online\" \/>\n<meta name=\"twitter:site\" content=\"@gran_online\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipe Gran\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-uyhara-barreira-pos-graduacao\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-uyhara-barreira-pos-graduacao\/\"},\"author\":{\"name\":\"Equipe Gran\",\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/#\/schema\/person\/c05f350f8ea43a7138aaffc6a87bc5e0\"},\"headline\":\"Conhe\u00e7a a hist\u00f3ria de Uyhara Barreira, aluna Gran P\u00f3s\",\"datePublished\":\"2025-04-16T20:37:38+00:00\",\"dateModified\":\"2025-04-25T16:21:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-uyhara-barreira-pos-graduacao\/\"},\"wordCount\":584,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-uyhara-barreira-pos-graduacao\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blog-es-static.infra.grancursosonline.com.br\/wp-content\/uploads\/2025\/04\/16105539\/depoimento-uyhara-barreira-pos-graduacao-social.jpg\",\"articleSection\":[\"Eu Sou Gran\",\"P\u00f3s-Gradua\u00e7\u00e3o Gran Faculdade\",\"\u00daltimas Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-uyhara-barreira-pos-graduacao\/#respond\"]}],\"copyrightYear\":\"2025\",\"copyrightHolder\":{\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-uyhara-barreira-pos-graduacao\/\",\"url\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-uyhara-barreira-pos-graduacao\/\",\"name\":\"Conhe\u00e7a a hist\u00f3ria de Uyhara Barreira, aluna Gran P\u00f3s\",\"isPartOf\":{\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-uyhara-barreira-pos-graduacao\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-uyhara-barreira-pos-graduacao\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blog-es-static.infra.grancursosonline.com.br\/wp-content\/uploads\/2025\/04\/16105539\/depoimento-uyhara-barreira-pos-graduacao-social.jpg\",\"datePublished\":\"2025-04-16T20:37:38+00:00\",\"dateModified\":\"2025-04-25T16:21:23+00:00\",\"description\":\"Uyhara Barreira revela como a flexibilidade da p\u00f3s-gradua\u00e7\u00e3o online em Direito Civil e Processo Civil da Gran Faculdade foi essencial para equilibrar sua rotina e carreira.\",\"breadcrumb\":{\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-uyhara-barreira-pos-graduacao\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-uyhara-barreira-pos-graduacao\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-uyhara-barreira-pos-graduacao\/#primaryimage\",\"url\":\"https:\/\/blog-es-static.infra.grancursosonline.com.br\/wp-content\/uploads\/2025\/04\/16105539\/depoimento-uyhara-barreira-pos-graduacao-social.jpg\",\"contentUrl\":\"https:\/\/blog-es-static.infra.grancursosonline.com.br\/wp-content\/uploads\/2025\/04\/16105539\/depoimento-uyhara-barreira-pos-graduacao-social.jpg\",\"width\":1001,\"height\":601,\"caption\":\"Uyhara Barreira\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-uyhara-barreira-pos-graduacao\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eu Sou Gran\",\"item\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimentos\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Conhe\u00e7a a hist\u00f3ria de Uyhara Barreira, aluna Gran P\u00f3s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/#website\",\"url\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/\",\"name\":\"Blog Gran Faculdade\",\"description\":\"Tudo sobre ensino superior, p\u00f3s-gradua\u00e7\u00e3o, enem e carreira.\",\"publisher\":{\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/#organization\",\"name\":\"Gran Cursos Online\",\"url\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/blog-es-static.infra.grancursosonline.com.br\/wp-content\/uploads\/2019\/08\/03123934\/logo.png\",\"contentUrl\":\"https:\/\/blog-es-static.infra.grancursosonline.com.br\/wp-content\/uploads\/2019\/08\/03123934\/logo.png\",\"width\":300,\"height\":57,\"caption\":\"Gran Cursos Online\"},\"image\":{\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/grancursosonline\/\",\"https:\/\/x.com\/gran_online\",\"https:\/\/www.instagram.com\/grancursosonline\/\",\"https:\/\/www.youtube.com\/user\/grancursostv\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/#\/schema\/person\/c05f350f8ea43a7138aaffc6a87bc5e0\",\"name\":\"Equipe Gran\",\"sameAs\":[\"http:\/\/www.grancursosonline.com.br\"],\"url\":\"https:\/\/faculdade.grancursosonline.com.br\/blog\/author\/hugo-oliveira\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Conhe\u00e7a a hist\u00f3ria de Uyhara Barreira, aluna Gran P\u00f3s","description":"Uyhara Barreira revela como a flexibilidade da p\u00f3s-gradua\u00e7\u00e3o online em Direito Civil e Processo Civil da Gran Faculdade foi essencial para equilibrar sua rotina e carreira.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-uyhara-barreira-pos-graduacao\/","og_locale":"pt_BR","og_type":"article","og_title":"Conhe\u00e7a a hist\u00f3ria de Uyhara Barreira, aluna Gran P\u00f3s","og_description":"Uyhara Barreira revela como a flexibilidade da p\u00f3s-gradua\u00e7\u00e3o online em Direito Civil e Processo Civil da Gran Faculdade foi essencial para equilibrar sua rotina e carreira.","og_url":"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-uyhara-barreira-pos-graduacao\/","og_site_name":"Blog Gran Faculdade","article_publisher":"https:\/\/www.facebook.com\/grancursosonline\/","article_published_time":"2025-04-16T20:37:38+00:00","article_modified_time":"2025-04-25T16:21:23+00:00","og_image":[{"width":511,"height":311,"url":"https:\/\/blog-es-static.infra.grancursosonline.com.br\/wp-content\/uploads\/2025\/04\/16105534\/depoimento-uyhara-barreira-pos-graduacao.jpg","type":"image\/jpeg"}],"author":"Equipe Gran","twitter_card":"summary_large_image","twitter_creator":"@gran_online","twitter_site":"@gran_online","twitter_misc":{"Written by":"Equipe Gran","Est. reading time":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-uyhara-barreira-pos-graduacao\/#article","isPartOf":{"@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-uyhara-barreira-pos-graduacao\/"},"author":{"name":"Equipe Gran","@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/#\/schema\/person\/c05f350f8ea43a7138aaffc6a87bc5e0"},"headline":"Conhe\u00e7a a hist\u00f3ria de Uyhara Barreira, aluna Gran P\u00f3s","datePublished":"2025-04-16T20:37:38+00:00","dateModified":"2025-04-25T16:21:23+00:00","mainEntityOfPage":{"@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-uyhara-barreira-pos-graduacao\/"},"wordCount":584,"commentCount":0,"publisher":{"@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-uyhara-barreira-pos-graduacao\/#primaryimage"},"thumbnailUrl":"https:\/\/blog-es-static.infra.grancursosonline.com.br\/wp-content\/uploads\/2025\/04\/16105539\/depoimento-uyhara-barreira-pos-graduacao-social.jpg","articleSection":["Eu Sou Gran","P\u00f3s-Gradua\u00e7\u00e3o Gran Faculdade","\u00daltimas Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-uyhara-barreira-pos-graduacao\/#respond"]}],"copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-uyhara-barreira-pos-graduacao\/","url":"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-uyhara-barreira-pos-graduacao\/","name":"Conhe\u00e7a a hist\u00f3ria de Uyhara Barreira, aluna Gran P\u00f3s","isPartOf":{"@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-uyhara-barreira-pos-graduacao\/#primaryimage"},"image":{"@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-uyhara-barreira-pos-graduacao\/#primaryimage"},"thumbnailUrl":"https:\/\/blog-es-static.infra.grancursosonline.com.br\/wp-content\/uploads\/2025\/04\/16105539\/depoimento-uyhara-barreira-pos-graduacao-social.jpg","datePublished":"2025-04-16T20:37:38+00:00","dateModified":"2025-04-25T16:21:23+00:00","description":"Uyhara Barreira revela como a flexibilidade da p\u00f3s-gradua\u00e7\u00e3o online em Direito Civil e Processo Civil da Gran Faculdade foi essencial para equilibrar sua rotina e carreira.","breadcrumb":{"@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-uyhara-barreira-pos-graduacao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-uyhara-barreira-pos-graduacao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-uyhara-barreira-pos-graduacao\/#primaryimage","url":"https:\/\/blog-es-static.infra.grancursosonline.com.br\/wp-content\/uploads\/2025\/04\/16105539\/depoimento-uyhara-barreira-pos-graduacao-social.jpg","contentUrl":"https:\/\/blog-es-static.infra.grancursosonline.com.br\/wp-content\/uploads\/2025\/04\/16105539\/depoimento-uyhara-barreira-pos-graduacao-social.jpg","width":1001,"height":601,"caption":"Uyhara Barreira"},{"@type":"BreadcrumbList","@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimento-uyhara-barreira-pos-graduacao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/faculdade.grancursosonline.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Eu Sou Gran","item":"https:\/\/faculdade.grancursosonline.com.br\/blog\/depoimentos\/"},{"@type":"ListItem","position":3,"name":"Conhe\u00e7a a hist\u00f3ria de Uyhara Barreira, aluna Gran P\u00f3s"}]},{"@type":"WebSite","@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/#website","url":"https:\/\/faculdade.grancursosonline.com.br\/blog\/","name":"Blog Gran Faculdade","description":"Tudo sobre ensino superior, p\u00f3s-gradua\u00e7\u00e3o, enem e carreira.","publisher":{"@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/faculdade.grancursosonline.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/#organization","name":"Gran Cursos Online","url":"https:\/\/faculdade.grancursosonline.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/blog-es-static.infra.grancursosonline.com.br\/wp-content\/uploads\/2019\/08\/03123934\/logo.png","contentUrl":"https:\/\/blog-es-static.infra.grancursosonline.com.br\/wp-content\/uploads\/2019\/08\/03123934\/logo.png","width":300,"height":57,"caption":"Gran Cursos Online"},"image":{"@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/grancursosonline\/","https:\/\/x.com\/gran_online","https:\/\/www.instagram.com\/grancursosonline\/","https:\/\/www.youtube.com\/user\/grancursostv"]},{"@type":"Person","@id":"https:\/\/faculdade.grancursosonline.com.br\/blog\/#\/schema\/person\/c05f350f8ea43a7138aaffc6a87bc5e0","name":"Equipe Gran","sameAs":["http:\/\/www.grancursosonline.com.br"],"url":"https:\/\/faculdade.grancursosonline.com.br\/blog\/author\/hugo-oliveira\/"}]}},"_links":{"self":[{"href":"https:\/\/faculdade.grancursosonline.com.br\/blog\/wp-json\/wp\/v2\/posts\/79753210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/faculdade.grancursosonline.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/faculdade.grancursosonline.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/faculdade.grancursosonline.com.br\/blog\/wp-json\/wp\/v2\/users\/486"}],"replies":[{"embeddable":true,"href":"https:\/\/faculdade.grancursosonline.com.br\/blog\/wp-json\/wp\/v2\/comments?post=79753210"}],"version-history":[{"count":2,"href":"https:\/\/faculdade.grancursosonline.com.br\/blog\/wp-json\/wp\/v2\/posts\/79753210\/revisions"}],"predecessor-version":[{"id":79753475,"href":"https:\/\/faculdade.grancursosonline.com.br\/blog\/wp-json\/wp\/v2\/posts\/79753210\/revisions\/79753475"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/faculdade.grancursosonline.com.br\/blog\/wp-json\/wp\/v2\/media\/79753212"}],"wp:attachment":[{"href":"https:\/\/faculdade.grancursosonline.com.br\/blog\/wp-json\/wp\/v2\/media?parent=79753210"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/faculdade.grancursosonline.com.br\/blog\/wp-json\/wp\/v2\/categories?post=79753210"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/faculdade.grancursosonline.com.br\/blog\/wp-json\/wp\/v2\/tags?post=79753210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}